
{"id":5397,"date":"2022-06-14T12:31:12","date_gmt":"2022-06-14T12:31:12","guid":{"rendered":"https:\/\/fello.pet\/?p=5397"},"modified":"2022-06-14T12:37:01","modified_gmt":"2022-06-14T12:37:01","slug":"barbet","status":"publish","type":"post","link":"https:\/\/fello.pet\/es\/barbet\/","title":{"rendered":"Barbet"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><strong><em>El Barbet es una mascota vers\u00e1til. Es alegre, amistoso e inteligente. Desde la primera infancia, hay que vigilar el comportamiento del perro, porque de adulto puede ser ego\u00edsta. A Barbet le encanta ser el centro de atenci\u00f3n y no le asusta el ruido. Se encari\u00f1a f\u00e1cil y r\u00e1pidamente con toda la familia y no le gusta pasar mucho tiempo solo.<\/em><\/strong><\/p>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-8f761849 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\"><h2 class=\"simpletoc-title\">Tabla de \u0421ontenido<\/h2>\n<ul class=\"simpletoc-list\">\n<li><a href=\"#informacion-de-la-raza\">Informaci\u00f3n de la Raza<\/a>\n<\/li>\n<li><a href=\"#fotos-de-la-raza\">Fotos de la Raza<\/a>\n<\/li>\n<li><a href=\"#historia-de-origen\">Historia de Origen<\/a>\n<\/li>\n<li><a href=\"#apariencia\">Apariencia<\/a>\n<\/li>\n<li><a href=\"#personaje\">Personaje<\/a>\n<\/li>\n<li><a href=\"#cuidado\">Cuidado<\/a>\n<\/li>\n<li><a href=\"#formacion\">Formaci\u00f3n<\/a>\n<\/li>\n<li><a href=\"#enfermedades-comunes\">Enfermedades Comunes<\/a>\n<\/li>\n<li><a href=\"#nutricion\">Nutrici\u00f3n<\/a>\n<\/li><\/ul><\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<h2 class=\"wp-block-heading\" id=\"informacion-de-la-raza\">Informaci\u00f3n de la Raza<\/h2>\n\n\n\n<figure class=\"wp-block-table alignleft\" style=\"font-size:18px\"><table class=\"has-fixed-layout\"><tbody><tr><td>Otro Nombre<\/td><td>Perro de aguas franc\u00e9s<\/td><\/tr><tr><td>Origen<\/td><td>Francia<\/td><\/tr><tr><td>Altura<\/td><td>Machos 58-65 cm<br>Hembras 53-61 cm<\/td><\/tr><tr><td>Peso<\/td><td>17-28 kg<\/td><\/tr><tr><td>Pelo<\/td><td>Rizado, largo<\/td><\/tr><tr><td>Color<\/td><td>P\u00e1lido, negro, gris, marr\u00f3n, blanco<\/td><\/tr><tr><td>Esperanza de Vida<\/td><td>13-15 a\u00f1os<\/td><\/tr><tr><td>Clasificaci\u00f3n FCI<\/td><td>Perros cobradores de caza &#8211; Perros levantadores de caza &#8211; Perros de agua<\/td><\/tr><tr><td>Grupo<\/td><td>Perros guardianes<\/td><\/tr><tr><td>Precio<\/td><td>$500-1000<\/td><\/tr><\/tbody><\/table><\/figure>\n<\/div>\n<\/div>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"fotos-de-la-raza\">Fotos de la Raza<\/h2>\n\n\n<div class=\"pgc-sgb-cb wp-block-pgcsimplygalleryblock-justified \" data-gallery-id=\"2f675960\"><div class=\"sgb-preloader\" id=\"pr_2f675960\">\n\t<div class=\"sgb-square\" style=\"background:#d4d4d4\"><\/div>\n\t<div class=\"sgb-square\" style=\"background:#d4d4d4\"><\/div>\n\t<div class=\"sgb-square\" style=\"background:#d4d4d4\"><\/div>\n\t<div class=\"sgb-square\" style=\"background:#d4d4d4\"><\/div><\/div><div class=\"simply-gallery-amp pgc_sgb_slider \"><noscript><div class=\"sgb-gallery\"><div class=\"sgb-item\"><a href=\"https:\/\/fello.pet\/?attachment_id=5394#main\" target=\"_blank\"><img decoding=\"async\" alt=\"Barbet\" width=\"675\" height=\"369\" loading=\"lazy\" src=\"https:\/\/fello.pet\/wp-content\/uploads\/2022\/06\/Barbet-1.png\" srcset=\",https:\/\/fello.pet\/wp-content\/uploads\/2022\/06\/Barbet-1.png 675w\" sizes=\"auto, 250px\"\/><\/a><\/div><div class=\"sgb-item\"><a href=\"https:\/\/fello.pet\/?attachment_id=5388#main\" target=\"_blank\"><img decoding=\"async\" alt=\"Barbet\" width=\"249\" height=\"400\" loading=\"lazy\" src=\"https:\/\/fello.pet\/wp-content\/uploads\/2022\/06\/Barbet-3-249x400.jpg\" srcset=\"https:\/\/fello.pet\/wp-content\/uploads\/2022\/06\/Barbet-3-249x400.jpg 249w,https:\/\/fello.pet\/wp-content\/uploads\/2022\/06\/Barbet-3.jpg 466w\" sizes=\"auto, 250px\"\/><\/a><\/div><div class=\"sgb-item\"><a href=\"https:\/\/fello.pet\/?attachment_id=5392#main\" target=\"_blank\"><img decoding=\"async\" alt=\"Barbet\" width=\"297\" height=\"400\" loading=\"lazy\" src=\"https:\/\/fello.pet\/wp-content\/uploads\/2022\/06\/Barbet-2-297x400.jpg\" srcset=\"https:\/\/fello.pet\/wp-content\/uploads\/2022\/06\/Barbet-2-297x400.jpg 297w,https:\/\/fello.pet\/wp-content\/uploads\/2022\/06\/Barbet-2.jpg 388w\" sizes=\"auto, 250px\"\/><\/a><\/div><div class=\"sgb-item\"><a href=\"https:\/\/fello.pet\/?attachment_id=5390#main\" target=\"_blank\"><img decoding=\"async\" alt=\"Barbet\" width=\"564\" height=\"375\" loading=\"lazy\" src=\"https:\/\/fello.pet\/wp-content\/uploads\/2022\/06\/Barbet-4.jpg\" srcset=\",https:\/\/fello.pet\/wp-content\/uploads\/2022\/06\/Barbet-4.jpg 564w\" sizes=\"auto, 250px\"\/><\/a><\/div><\/div><\/noscript><\/div><script type=\"application\/json\" class=\"sgb-data\">{\"lastRowFill\":true,\"collectionThumbRecomendedHeight\":300,\"collectionThumbMiniScreenScale\":true,\"externalLink\":false,\"collectionThumbSubMenuDownload\":false,\"collectionThumbSubMenuShare\":false,\"galleryType\":\"pgc_sgb_justified\",\"galleryId\":\"2f675960\",\"images\":[{\"id\":5394,\"title\":\"Barbet\",\"url\":\"https:\/\/fello.pet\/wp-content\/uploads\/2022\/06\/Barbet-1.png\",\"link\":\"https:\/\/fello.pet\/?attachment_id=5394#main\",\"alt\":\"Barbet\",\"description\":\"\",\"caption\":\"\",\"mime\":\"image\/png\",\"type\":\"image\",\"width\":675,\"height\":369,\"sizes\":{\"thumbnail\":{\"url\":\"https:\/\/fello.pet\/wp-content\/uploads\/2022\/06\/Barbet-1-280x280.png\",\"height\":280,\"width\":280,\"orientation\":\"landscape\"},\"full\":{\"url\":\"https:\/\/fello.pet\/wp-content\/uploads\/2022\/06\/Barbet-1.png\",\"height\":369,\"width\":675,\"orientation\":\"landscape\"}},\"meta\":false,\"postlink\":\"https:\/\/fello.pet\/?attachment_id=5394#main\"},{\"id\":5388,\"title\":\"Barbet\",\"url\":\"https:\/\/fello.pet\/wp-content\/uploads\/2022\/06\/Barbet-3.jpg\",\"link\":\"https:\/\/fello.pet\/?attachment_id=5388#main\",\"alt\":\"Barbet\",\"description\":\"\",\"caption\":\"\",\"mime\":\"image\/jpeg\",\"type\":\"image\",\"width\":466,\"height\":750,\"sizes\":{\"thumbnail\":{\"url\":\"https:\/\/fello.pet\/wp-content\/uploads\/2022\/06\/Barbet-3-280x280.jpg\",\"height\":280,\"width\":280,\"orientation\":\"landscape\"},\"medium\":{\"url\":\"https:\/\/fello.pet\/wp-content\/uploads\/2022\/06\/Barbet-3-249x400.jpg\",\"height\":400,\"width\":249,\"orientation\":\"portrait\"},\"full\":{\"url\":\"https:\/\/fello.pet\/wp-content\/uploads\/2022\/06\/Barbet-3.jpg\",\"height\":750,\"width\":466,\"orientation\":\"portrait\"}},\"meta\":false,\"postlink\":\"https:\/\/fello.pet\/?attachment_id=5388#main\"},{\"id\":5392,\"title\":\"Barbet\",\"url\":\"https:\/\/fello.pet\/wp-content\/uploads\/2022\/06\/Barbet-2.jpg\",\"link\":\"https:\/\/fello.pet\/?attachment_id=5392#main\",\"alt\":\"Barbet\",\"description\":\"\",\"caption\":\"\",\"mime\":\"image\/jpeg\",\"type\":\"image\",\"width\":388,\"height\":522,\"sizes\":{\"thumbnail\":{\"url\":\"https:\/\/fello.pet\/wp-content\/uploads\/2022\/06\/Barbet-2-280x280.jpg\",\"height\":280,\"width\":280,\"orientation\":\"landscape\"},\"medium\":{\"url\":\"https:\/\/fello.pet\/wp-content\/uploads\/2022\/06\/Barbet-2-297x400.jpg\",\"height\":400,\"width\":297,\"orientation\":\"portrait\"},\"full\":{\"url\":\"https:\/\/fello.pet\/wp-content\/uploads\/2022\/06\/Barbet-2.jpg\",\"height\":522,\"width\":388,\"orientation\":\"portrait\"}},\"meta\":false,\"postlink\":\"https:\/\/fello.pet\/?attachment_id=5392#main\"},{\"id\":5390,\"title\":\"Barbet\",\"url\":\"https:\/\/fello.pet\/wp-content\/uploads\/2022\/06\/Barbet-4.jpg\",\"link\":\"https:\/\/fello.pet\/?attachment_id=5390#main\",\"alt\":\"Barbet\",\"description\":\"\",\"caption\":\"\",\"mime\":\"image\/jpeg\",\"type\":\"image\",\"width\":564,\"height\":375,\"sizes\":{\"thumbnail\":{\"url\":\"https:\/\/fello.pet\/wp-content\/uploads\/2022\/06\/Barbet-4-280x280.jpg\",\"height\":280,\"width\":280,\"orientation\":\"landscape\"},\"full\":{\"url\":\"https:\/\/fello.pet\/wp-content\/uploads\/2022\/06\/Barbet-4.jpg\",\"height\":375,\"width\":564,\"orientation\":\"landscape\"}},\"meta\":false,\"postlink\":\"https:\/\/fello.pet\/?attachment_id=5390#main\"}],\"itemsMetaDataCollection\":[],\"galleryData\":\"{\\u0022pageMode\\u0022:false,\\u0022lastRowFill\\u0022:false,\\u0022collectionThumbRecomendedHeight\\u0022:200,\\u0022collectionThumbMiniScreenScale\\u0022:false,\\u0022thumbSpacing\\u0022:5,\\u0022thumbMobileSpacing\\u0022:5,\\u0022externalLink\\u0022:true,\\u0022externalLinkDefName\\u0022:\\u0022Read More\\u0022,\\u0022externalLinkTextColor\\u0022:\\u0022rgba(0,0,0,1)\\u0022,\\u0022externalLinkBgColor\\u0022:\\u0022rgba(255,255,255,1)\\u0022,\\u0022externalLinkFontSize\\u0022:18,\\u0022captions\\u0022:true,\\u0022captionSrc\\u0022:\\u0022caption\\u0022,\\u0022captionHAlign\\u0022:\\u0022top\\u0022,\\u0022collectionthumbHoverTitleFontSize\\u0022:18,\\u0022collectionthumbRoundedCorners\\u0022:0,\\u0022collectionthumbHoverTitleTextColor\\u0022:\\u0022rgba(255,255,255,1)\\u0022,\\u0022collectionthumbHoverTitleTextBgColor\\u0022:\\u0022rgba(0,0,0,0.8)\\u0022,\\u0022collectionthumbHoverBgColor\\u0022:\\u0022rgba(0,0,0,0.4)\\u0022,\\u0022collectionThumbSubMenuDownload\\u0022:true,\\u0022collectionThumbSubMenuShare\\u0022:true,\\u0022collectionThumbSubMenuBgColor\\u0022:\\u0022rgba(0,0,0,0.4)\\u0022,\\u0022collectionThumbSubMenuBgColorHover\\u0022:\\u0022rgba(255,255,255,1)\\u0022,\\u0022collectionThumbSubMenuIconColor\\u0022:\\u0022rgba(255,255,255,1)\\u0022,\\u0022collectionThumbSubMenuIconColorHover\\u0022:\\u0022rgba(0,0,0,1)\\u0022,\\u0022settingsModalIsOpen\\u0022:false,\\u0022galleryType\\u0022:\\u0022pgc_sgb_justified\\u0022,\\u0022align\\u0022:\\u0022\\u0022,\\u0022galleryId\\u0022:\\u00222f675960\\u0022,\\u0022tagsListCustomMode\\u0022:false,\\u0022initGalleryByFirstTag\\u0022:false,\\u0022deepLinkingForTag\\u0022:false,\\u0022galleryTagsList\\u0022:[],\\u0022useClobalSettings\\u0022:true,\\u0022orderBy\\u0022:\\u0022custom\\u0022,\\u0022deepLinking\\u0022:false,\\u0022useLightbox\\u0022:true,\\u0022thumbClickAction\\u0022:\\u0022useLightbox\\u0022,\\u0022numItemsDisplayed\\u0022:0,\\u0022lazyLoading\\u0022:true,\\u0022contentNoPadding\\u0022:false,\\u0022galleryPreloaderColor\\u0022:\\u0022rgba(230,230,230,1)\\u0022,\\u0022galleryBgColor\\u0022:\\u0022rgba(0,0,0,0)\\u0022,\\u0022galleryBorderRadius\\u0022:0,\\u0022customCSS\\u0022:\\u0022\\u0022,\\u0022itemsPerPage\\u0022:20,\\u0022loadMoreDefName\\u0022:\\u0022Load More\\u0022,\\u0022loadMoreFontSize\\u0022:16,\\u0022loadMoreTextColor\\u0022:\\u0022rgba(255,255,255,1)\\u0022,\\u0022loadMoreBgColor\\u0022:\\u0022rgba(0,0,0,1)\\u0022,\\u0022tagsFilter\\u0022:false,\\u0022tagCloudAll\\u0022:\\u0022All\\u0022,\\u0022tagCloudBgColor\\u0022:\\u0022rgba(153,153,153,1)\\u0022,\\u0022tagCloudBgColorOver\\u0022:\\u0022rgba(253,253,253,1)\\u0022,\\u0022tagCloudTextColor\\u0022:\\u0022rgba(253,253,253,1)\\u0022,\\u0022tagCloudTextColorOver\\u0022:\\u0022rgba(153,153,153,1)\\u0022,\\u0022tagCloudFontSize\\u0022:16,\\u0022modaBgColor\\u0022:\\u0022rgba(0,0,0,0.8)\\u0022,\\u0022modalIconColor\\u0022:\\u0022rgba(255,255,255,1)\\u0022,\\u0022modalIconColorHover\\u0022:\\u0022rgba(255,255,255,0.8)\\u0022,\\u0022shareFacebook\\u0022:true,\\u0022shareTwitter\\u0022:true,\\u0022sharePinterest\\u0022:true,\\u0022sliderItemDownload\\u0022:true,\\u0022shareCopyLink\\u0022:true,\\u0022sharePost\\u0022:\\u0022sharelink\\u0022,\\u0022copyRProtection\\u0022:false,\\u0022copyRAlert\\u0022:\\u0022Hello, this photo is mine!\\u0022,\\u0022sliderScrollNavi\\u0022:false,\\u0022sliderFullSizeViewMode\\u0022:false,\\u0022sliderNextPrevAnimation\\u0022:\\u0022animation\\u0022,\\u0022galleryScrollPositionControll\\u0022:false,\\u0022sliderVideoAutoPlay\\u0022:false,\\u0022sliderTryPlayNext\\u0022:false,\\u0022sliderVideoLoop\\u0022:false,\\u0022sliderItemCounterEnable\\u0022:true,\\u0022sliderCaptionSrc\\u0022:\\u0022caption\\u0022,\\u0022sliderItemTitleEnable\\u0022:false,\\u0022sliderItemTitleFontSize\\u0022:18,\\u0022sliderItemTitleTextColor\\u0022:\\u0022rgba(255,255,255,1)\\u0022,\\u0022itemCounterColor\\u0022:\\u0022rgba(255,255,255,1)\\u0022,\\u0022sliderThumbBarEnable\\u0022:true,\\u0022sliderThumbBarHoverColor\\u0022:\\u0022rgba(240,240,240,1)\\u0022,\\u0022sliderBgColor\\u0022:\\u0022rgba(0,0,0,0.8)\\u0022,\\u0022sliderPreloaderColor\\u0022:\\u0022rgba(240,240,240,1)\\u0022,\\u0022sliderHeaderFooterBgColor\\u0022:\\u0022rgba(0,0,0,0.4)\\u0022,\\u0022sliderNavigationColor\\u0022:\\u0022rgba(0,0,0,1)\\u0022,\\u0022sliderNavigationColorOver\\u0022:\\u0022rgba(255,255,255,1)\\u0022,\\u0022sliderNavigationIconColor\\u0022:\\u0022rgba(255,255,255,1)\\u0022,\\u0022sliderNavigationIconColorOver\\u0022:\\u0022rgba(0,0,0,1)\\u0022,\\u0022sliderSlideshow\\u0022:true,\\u0022sliderSlideshowDelay\\u0022:8,\\u0022slideshowIndicatorColor\\u0022:\\u0022rgba(255,255,255,1)\\u0022,\\u0022slideshowIndicatorColorBg\\u0022:\\u0022rgba(255,255,255,0.5)\\u0022,\\u0022sliderThumbSubMenuBackgroundColor\\u0022:\\u0022rgba(255,255,255,0)\\u0022,\\u0022sliderThumbSubMenuBackgroundColorOver\\u0022:\\u0022rgba(255,255,255,1)\\u0022,\\u0022sliderThumbSubMenuIconColor\\u0022:\\u0022rgba(255,255,255,1)\\u0022,\\u0022sliderThumbSubMenuIconHoverColor\\u0022:\\u0022rgba(0,0,0,1)\\u0022,\\u0022sliderSocialShareEnabled\\u0022:true,\\u0022sliderZoomEnable\\u0022:true,\\u0022sliderFullscreenEnabled\\u0022:true,\\u0022skin\\u0022:\\u0022justified\\u0022}\",\"useClobalSettings\":true,\"sharePost\":\"postlink\",\"sliderSocialShareEnabled\":false}<\/script><script>(function(){if(window.PGC_SGB && window.PGC_SGB.searcher){window.PGC_SGB.searcher.initBlocks()}})()<\/script><\/div>\n\n\n<h2 class=\"wp-block-heading\" id=\"historia-de-origen\">Historia de Origen<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Los perros de agua son conocidos desde la antig\u00fcedad en muchos pa\u00edses del mundo. A menudo se les representaba en pinturas cerca de masas de agua porque estos perros son excelentes nadadores. El Barbet desciende de perros como el Caniche, el Bichon Frise y el Perro de Agua Americano.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El primer club de aficionados a la raza se form\u00f3 en el siglo XIX, cuando la raza fue reconocida oficialmente. Los perros eran utilizados activamente por los marineros que sal\u00edan de viaje y los cazadores de fauna.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La Primera y la Segunda Guerra Mundial afectaron negativamente al desarrollo y al n\u00famero de barbos. En esa \u00e9poca, la raza estaba al borde de la extinci\u00f3n. Los franceses trabajaron en la restauraci\u00f3n y selecci\u00f3n de la raza, que finalmente consiguieron salvarla en la d\u00e9cada de 1980. Ahora los perros se presentan en exposiciones mundiales y son muy populares como mascotas.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"apariencia\">Apariencia<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">El Barbet tiene un tama\u00f1o mediano, cabeza redonda, nariz corta y orejas largas y ca\u00eddas. Las patas del perro est\u00e1n adaptadas para nadar f\u00e1cilmente en cualquier clima. Son grandes y redondeadas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El pelaje es largo, rizado e impermeable. El pelaje puede tener diferentes colores \u2013 negro, gris, blanco, p\u00e1lido, marr\u00f3n. Se permiten marcas de otros colores y de color mixto.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Los machos son ligeramente m\u00e1s altos y gordos que las hembras. El crecimiento de los machos es de 58-65 cm, la altura de las hembras \u2013 53-61 cm. El peso es de unos 17-28 kg.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La cola del Barbet es de baja implantaci\u00f3n, al final un poco torcida. El cuerpo es armonioso, con buena musculatura y fuertes m\u00fasculos.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"personaje\">Personaje<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">El Barbet es una mascota vers\u00e1til. Es alegre, amistoso e inteligente. Desde la primera infancia, hay que vigilar el comportamiento del perro, porque de adulto puede ser ego\u00edsta.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A Barbet le encanta ser el centro de atenci\u00f3n y no le asusta el ruido. Se encari\u00f1a f\u00e1cil y r\u00e1pidamente con toda la familia y no le gusta pasar mucho tiempo solo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Tienen un cari\u00f1o especial por los escolares. Acompa\u00f1an de buen grado al ni\u00f1o a la escuela y lo esperan al salir de ella.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Tambi\u00e9n tienen cualidades de guardi\u00e1n perfectamente desarrolladas. Pueden vigilar la casa y la propiedad. Al criar un perro, debe estar preparado para el hecho de que es muy activo. Puede ensuciarse y ensuciar a menudo. A veces pueden ser muy tercos y voluntariosos.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"cuidado\">Cuidado<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Barbet puede vivir f\u00e1cilmente en un apartamento si camina regularmente. Alrededor de tres veces al d\u00eda con el ejercicio vigoroso. Vale la pena recordar el prop\u00f3sito principal del perro \u2013 la nataci\u00f3n. En verano, se puede equipar una piscina especial o salir juntos al lago.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La dieta del perro requiere un cuidado especial. Al fin y al cabo, son propensos a la obesidad. El pelo grueso y largo debe cepillarse a diario. De ello depende su buen aspecto y estado. Por su rizado natural, pueden aparecer enredos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Las orejas del perro son un punto d\u00e9bil. Pueden ser propensas a las infecciones. Por ello, conviene inspeccionarse y limpiarse regularmente. Los ojos y la boca deben examinarse y limpiarse una vez a la semana, si es necesario.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El barbet casi nunca se muda, pero a veces puede recortarse para que parezca aseado. Como los barbets son muy activos y pueden ensuciarse a menudo, deben ser ba\u00f1ados una vez al mes o cuando sea necesario con champ\u00fas especiales.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"formacion\">Formaci\u00f3n<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">El adiestramiento y la educaci\u00f3n de un perro deben comenzar desde los primeros d\u00edas de la llegada del cachorro al hogar. El adiestramiento debe durar toda la vida. Los barbos requieren una estimulaci\u00f3n f\u00edsica y mental constante para mantener su tono. Estos perros son f\u00e1ciles de adiestrar, pero siempre sienten la autoridad y el car\u00e1cter fuerte del due\u00f1o.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Pueden ser testarudos y no querer seguir las \u00f3rdenes. En tales situaciones, hay que animar al perro a obedecer con una entonaci\u00f3n seria. Un buen extra despu\u00e9s de cada entrenamiento puede ser una sabrosa recompensa. Adem\u00e1s, no sea taca\u00f1o con los elogios y el afecto.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"enfermedades-comunes\">Enfermedades Comunes<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">La salud del Barbet es generalmente fuerte; sin embargo, es com\u00fan que tengan enfermedades como displasia de cadera, hernia y maloclusi\u00f3n.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Es necesario recordar las vacunas y el tratamiento del pelaje contra los par\u00e1sitos. Las visitas regulares al m\u00e9dico y el cuidado adecuado de la mascota.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"nutricion\">Nutrici\u00f3n<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">La base de la dieta del Barbet debe ser la carne (magra), las verduras, las frutas y los productos l\u00e1cteos. El perro debe tener siempre libre acceso a agua limpia. Si decide alimentar a los alimentos secos, es mejor si es caro y de alta calidad con todos los minerales y vitaminas \u00fatiles.<\/p>\n\n\n\n","protected":false},"excerpt":{"rendered":"<p>El Barbet es una mascota vers\u00e1til. Es alegre, amistoso e inteligente. Desde la primera infancia, hay que vigilar el comportamiento del perro, porque de adulto puede ser ego\u00edsta. A Barbet le encanta ser el centro de atenci\u00f3n y no le asusta el ruido. Se encari\u00f1a f\u00e1cil y r\u00e1pidamente con toda la familia y no le [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":5395,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"pgc_sgb_lightbox_settings":"","footnotes":""},"categories":[271],"tags":[237,226,250,247],"class_list":["post-5397","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-razas-de-perros","tag-razas-de-perros-franceses","tag-razas-de-perros-guardianes","tag-razas-de-perros-medianos","tag-razas-de-perros-rizados"],"acf":[],"_links":{"self":[{"href":"https:\/\/fello.pet\/es\/wp-json\/wp\/v2\/posts\/5397","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/fello.pet\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/fello.pet\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/fello.pet\/es\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/fello.pet\/es\/wp-json\/wp\/v2\/comments?post=5397"}],"version-history":[{"count":1,"href":"https:\/\/fello.pet\/es\/wp-json\/wp\/v2\/posts\/5397\/revisions"}],"predecessor-version":[{"id":5398,"href":"https:\/\/fello.pet\/es\/wp-json\/wp\/v2\/posts\/5397\/revisions\/5398"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/fello.pet\/es\/wp-json\/wp\/v2\/media\/5395"}],"wp:attachment":[{"href":"https:\/\/fello.pet\/es\/wp-json\/wp\/v2\/media?parent=5397"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/fello.pet\/es\/wp-json\/wp\/v2\/categories?post=5397"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/fello.pet\/es\/wp-json\/wp\/v2\/tags?post=5397"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}