
{"id":3274,"date":"2022-05-10T11:16:33","date_gmt":"2022-05-10T11:16:33","guid":{"rendered":"https:\/\/fello.pet\/?p=3274"},"modified":"2022-05-10T11:23:55","modified_gmt":"2022-05-10T11:23:55","slug":"hokkaido","status":"publish","type":"post","link":"https:\/\/fello.pet\/es\/hokkaido\/","title":{"rendered":"Hokkaido"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><strong><em>El Hokkaido es una raza de perro con una personalidad complicada que incluye cualidades opuestas. Son inteligentes, incre\u00edblemente inteligentes, cari\u00f1osos y, al mismo tiempo, alegres y peligrosos. Para su amo, el Hokkaido ser\u00e1 una monta\u00f1a y nunca har\u00e1 da\u00f1o. Todos los perros necesitan amor, cuidados y una excelente educaci\u00f3n; as\u00ed no se consigue un perro incontrolable y agresivo.<\/em><\/strong><\/p>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-8f761849 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\"><h2 class=\"simpletoc-title\">Tabla de \u0421ontenido<\/h2>\n<ul class=\"simpletoc-list\">\n<li><a href=\"#informacion-de-la-raza\">Informaci\u00f3n de la Raza<\/a>\n<\/li>\n<li><a href=\"#fotos-de-la-raza\">Fotos de la Raza<\/a>\n<\/li>\n<li><a href=\"#historia-de-origen\">Historia de Origen<\/a>\n<\/li>\n<li><a href=\"#apariencia\">Apariencia<\/a>\n<\/li>\n<li><a href=\"#personaje\">Personaje<\/a>\n<\/li>\n<li><a href=\"#cuidado\">Cuidado<\/a>\n<\/li>\n<li><a href=\"#formacion\">Formaci\u00f3n<\/a>\n<\/li>\n<li><a href=\"#enfermedades-comunes\">Enfermedades Comunes<\/a>\n<\/li>\n<li><a href=\"#nutricion\">Nutrici\u00f3n<\/a>\n<\/li><\/ul><\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<h2 class=\"wp-block-heading\" id=\"informacion-de-la-raza\">Informaci\u00f3n de la Raza<\/h2>\n\n\n\n<figure class=\"wp-block-table alignleft\" style=\"font-size:18px\"><table class=\"has-fixed-layout\"><tbody><tr><td>Otro Nombre<\/td><td>D\u014d-ken, Ainu-ken,<br>Ainu Dog<\/td><\/tr><tr><td>Origen<\/td><td>Jap\u00f3n<\/td><\/tr><tr><td>Altura<\/td><td>Machos 48,5-51,5 cm<br>Hembras 45,5-48,5 cm<\/td><\/tr><tr><td>Peso<\/td><td>20-30 kg<\/td><\/tr><tr><td>Pelo<\/td><td>Doble<\/td><\/tr><tr><td>Color<\/td><td>S\u00e9samo, tigre, rojo, negro, negro con matices rojos, blanco<\/td><\/tr><tr><td>Esperanza de Vida<\/td><td>10-15 a\u00f1os<\/td><\/tr><tr><td>Clasificaci\u00f3n FCI<\/td><td>Perros tipo spitz y tipo primitivo<\/td><\/tr><tr><td>Grupo<\/td><td>Perros de caza, perros guardianes<\/td><\/tr><tr><td>Precio<\/td><td>Desde $1300<\/td><\/tr><\/tbody><\/table><\/figure>\n<\/div>\n<\/div>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"fotos-de-la-raza\">Fotos de la Raza<\/h2>\n\n\n<div class=\"pgc-sgb-cb wp-block-pgcsimplygalleryblock-justified \" data-gallery-id=\"15927901\"><div class=\"sgb-preloader\" id=\"pr_15927901\">\n\t<div class=\"sgb-square\" style=\"background:#d4d4d4\"><\/div>\n\t<div class=\"sgb-square\" style=\"background:#d4d4d4\"><\/div>\n\t<div class=\"sgb-square\" style=\"background:#d4d4d4\"><\/div>\n\t<div class=\"sgb-square\" style=\"background:#d4d4d4\"><\/div><\/div><div class=\"simply-gallery-amp pgc_sgb_slider \"><noscript><div class=\"sgb-gallery\"><div class=\"sgb-item\"><a href=\"https:\/\/fello.pet\/?attachment_id=3264#main\" target=\"_blank\"><img decoding=\"async\" alt=\"Hokkaido\" width=\"564\" height=\"376\" loading=\"lazy\" src=\"https:\/\/fello.pet\/wp-content\/uploads\/2022\/05\/Hokkaido-1.jpg\" srcset=\",https:\/\/fello.pet\/wp-content\/uploads\/2022\/05\/Hokkaido-1.jpg 564w\" sizes=\"auto, 250px\"\/><\/a><\/div><div class=\"sgb-item\"><a href=\"https:\/\/fello.pet\/?attachment_id=3270#main\" target=\"_blank\"><img decoding=\"async\" alt=\"Hokkaido\" width=\"294\" height=\"400\" loading=\"lazy\" src=\"https:\/\/fello.pet\/wp-content\/uploads\/2022\/05\/Hokkaido-2-294x400.jpg\" srcset=\"https:\/\/fello.pet\/wp-content\/uploads\/2022\/05\/Hokkaido-2-294x400.jpg 294w,https:\/\/fello.pet\/wp-content\/uploads\/2022\/05\/Hokkaido-2.jpg 500w\" sizes=\"auto, 250px\"\/><\/a><\/div><div class=\"sgb-item\"><a href=\"https:\/\/fello.pet\/?attachment_id=3266#main\" target=\"_blank\"><img decoding=\"async\" alt=\"Hokkaido\" width=\"439\" height=\"400\" loading=\"lazy\" src=\"https:\/\/fello.pet\/wp-content\/uploads\/2022\/05\/Hokkaido-4-439x400.jpg\" srcset=\"https:\/\/fello.pet\/wp-content\/uploads\/2022\/05\/Hokkaido-4-439x400.jpg 439w,https:\/\/fello.pet\/wp-content\/uploads\/2022\/05\/Hokkaido-4.jpg 563w\" sizes=\"auto, 250px\"\/><\/a><\/div><div class=\"sgb-item\"><a href=\"https:\/\/fello.pet\/?attachment_id=3268#main\" target=\"_blank\"><img decoding=\"async\" alt=\"Hokkaido\" width=\"512\" height=\"371\" loading=\"lazy\" src=\"https:\/\/fello.pet\/wp-content\/uploads\/2022\/05\/Hokkaido-3.jpg\" srcset=\",https:\/\/fello.pet\/wp-content\/uploads\/2022\/05\/Hokkaido-3.jpg 512w\" sizes=\"auto, 250px\"\/><\/a><\/div><\/div><\/noscript><\/div><script type=\"application\/json\" class=\"sgb-data\">{\"lastRowFill\":true,\"collectionThumbRecomendedHeight\":300,\"collectionThumbMiniScreenScale\":true,\"externalLink\":false,\"collectionThumbSubMenuDownload\":false,\"collectionThumbSubMenuShare\":false,\"galleryType\":\"pgc_sgb_justified\",\"galleryId\":\"15927901\",\"images\":[{\"id\":3264,\"title\":\"Hokkaido\",\"url\":\"https:\/\/fello.pet\/wp-content\/uploads\/2022\/05\/Hokkaido-1.jpg\",\"link\":\"https:\/\/fello.pet\/?attachment_id=3264#main\",\"alt\":\"Hokkaido\",\"description\":\"\",\"caption\":\"\",\"mime\":\"image\/jpeg\",\"type\":\"image\",\"width\":564,\"height\":376,\"sizes\":{\"thumbnail\":{\"url\":\"https:\/\/fello.pet\/wp-content\/uploads\/2022\/05\/Hokkaido-1-280x280.jpg\",\"height\":280,\"width\":280,\"orientation\":\"landscape\"},\"full\":{\"url\":\"https:\/\/fello.pet\/wp-content\/uploads\/2022\/05\/Hokkaido-1.jpg\",\"height\":376,\"width\":564,\"orientation\":\"landscape\"}},\"meta\":false,\"postlink\":\"https:\/\/fello.pet\/?attachment_id=3264#main\"},{\"id\":3270,\"title\":\"Hokkaido\",\"url\":\"https:\/\/fello.pet\/wp-content\/uploads\/2022\/05\/Hokkaido-2.jpg\",\"link\":\"https:\/\/fello.pet\/?attachment_id=3270#main\",\"alt\":\"Hokkaido\",\"description\":\"\",\"caption\":\"\",\"mime\":\"image\/jpeg\",\"type\":\"image\",\"width\":500,\"height\":680,\"sizes\":{\"thumbnail\":{\"url\":\"https:\/\/fello.pet\/wp-content\/uploads\/2022\/05\/Hokkaido-2-280x280.jpg\",\"height\":280,\"width\":280,\"orientation\":\"landscape\"},\"medium\":{\"url\":\"https:\/\/fello.pet\/wp-content\/uploads\/2022\/05\/Hokkaido-2-294x400.jpg\",\"height\":400,\"width\":294,\"orientation\":\"portrait\"},\"full\":{\"url\":\"https:\/\/fello.pet\/wp-content\/uploads\/2022\/05\/Hokkaido-2.jpg\",\"height\":680,\"width\":500,\"orientation\":\"portrait\"}},\"meta\":false,\"postlink\":\"https:\/\/fello.pet\/?attachment_id=3270#main\"},{\"id\":3266,\"title\":\"Hokkaido\",\"url\":\"https:\/\/fello.pet\/wp-content\/uploads\/2022\/05\/Hokkaido-4.jpg\",\"link\":\"https:\/\/fello.pet\/?attachment_id=3266#main\",\"alt\":\"Hokkaido\",\"description\":\"\",\"caption\":\"\",\"mime\":\"image\/jpeg\",\"type\":\"image\",\"width\":563,\"height\":513,\"sizes\":{\"thumbnail\":{\"url\":\"https:\/\/fello.pet\/wp-content\/uploads\/2022\/05\/Hokkaido-4-280x280.jpg\",\"height\":280,\"width\":280,\"orientation\":\"landscape\"},\"medium\":{\"url\":\"https:\/\/fello.pet\/wp-content\/uploads\/2022\/05\/Hokkaido-4-439x400.jpg\",\"height\":400,\"width\":439,\"orientation\":\"landscape\"},\"full\":{\"url\":\"https:\/\/fello.pet\/wp-content\/uploads\/2022\/05\/Hokkaido-4.jpg\",\"height\":513,\"width\":563,\"orientation\":\"landscape\"}},\"meta\":false,\"postlink\":\"https:\/\/fello.pet\/?attachment_id=3266#main\"},{\"id\":3268,\"title\":\"Hokkaido\",\"url\":\"https:\/\/fello.pet\/wp-content\/uploads\/2022\/05\/Hokkaido-3.jpg\",\"link\":\"https:\/\/fello.pet\/?attachment_id=3268#main\",\"alt\":\"Hokkaido\",\"description\":\"\",\"caption\":\"\",\"mime\":\"image\/jpeg\",\"type\":\"image\",\"width\":512,\"height\":371,\"sizes\":{\"thumbnail\":{\"url\":\"https:\/\/fello.pet\/wp-content\/uploads\/2022\/05\/Hokkaido-3-280x280.jpg\",\"height\":280,\"width\":280,\"orientation\":\"landscape\"},\"full\":{\"url\":\"https:\/\/fello.pet\/wp-content\/uploads\/2022\/05\/Hokkaido-3.jpg\",\"height\":371,\"width\":512,\"orientation\":\"landscape\"}},\"meta\":false,\"postlink\":\"https:\/\/fello.pet\/?attachment_id=3268#main\"}],\"itemsMetaDataCollection\":[],\"galleryData\":\"{\\u0022pageMode\\u0022:false,\\u0022lastRowFill\\u0022:true,\\u0022collectionThumbRecomendedHeight\\u0022:300,\\u0022collectionThumbMiniScreenScale\\u0022:true,\\u0022thumbSpacing\\u0022:5,\\u0022externalLink\\u0022:false,\\u0022externalLinkDefName\\u0022:\\u0022Read More\\u0022,\\u0022externalLinkTextColor\\u0022:\\u0022rgba(0,0,0,1)\\u0022,\\u0022externalLinkBgColor\\u0022:\\u0022rgba(255,255,255,1)\\u0022,\\u0022externalLinkFontSize\\u0022:18,\\u0022captions\\u0022:true,\\u0022captionSrc\\u0022:\\u0022caption\\u0022,\\u0022captionHAlign\\u0022:\\u0022top\\u0022,\\u0022collectionthumbHoverTitleFontSize\\u0022:18,\\u0022collectionthumbRoundedCorners\\u0022:0,\\u0022collectionthumbHoverTitleTextColor\\u0022:\\u0022rgba(255,255,255,1)\\u0022,\\u0022collectionthumbHoverTitleTextBgColor\\u0022:\\u0022rgba(0,0,0,0.8)\\u0022,\\u0022collectionthumbHoverBgColor\\u0022:\\u0022rgba(0,0,0,0.4)\\u0022,\\u0022collectionThumbSubMenuDownload\\u0022:false,\\u0022collectionThumbSubMenuShare\\u0022:false,\\u0022collectionThumbSubMenuBgColor\\u0022:\\u0022rgba(0,0,0,0.4)\\u0022,\\u0022collectionThumbSubMenuBgColorHover\\u0022:\\u0022rgba(255,255,255,1)\\u0022,\\u0022collectionThumbSubMenuIconColor\\u0022:\\u0022rgba(255,255,255,1)\\u0022,\\u0022collectionThumbSubMenuIconColorHover\\u0022:\\u0022rgba(0,0,0,1)\\u0022,\\u0022settingsModalIsOpen\\u0022:false,\\u0022galleryType\\u0022:\\u0022pgc_sgb_justified\\u0022,\\u0022align\\u0022:\\u0022\\u0022,\\u0022galleryId\\u0022:\\u002215927901\\u0022,\\u0022tagsListCustomMode\\u0022:false,\\u0022initGalleryByFirstTag\\u0022:false,\\u0022deepLinkingForTag\\u0022:false,\\u0022galleryTagsList\\u0022:[],\\u0022useClobalSettings\\u0022:true,\\u0022orderBy\\u0022:\\u0022custom\\u0022,\\u0022deepLinking\\u0022:false,\\u0022useLightbox\\u0022:true,\\u0022thumbClickAction\\u0022:\\u0022useLightbox\\u0022,\\u0022numItemsDisplayed\\u0022:0,\\u0022lazyLoading\\u0022:true,\\u0022contentNoPadding\\u0022:false,\\u0022galleryPreloaderColor\\u0022:\\u0022rgba(230,230,230,1)\\u0022,\\u0022galleryBgColor\\u0022:\\u0022rgba(0,0,0,0)\\u0022,\\u0022galleryBorderRadius\\u0022:0,\\u0022customCSS\\u0022:\\u0022\\u0022,\\u0022itemsPerPage\\u0022:20,\\u0022loadMoreDefName\\u0022:\\u0022Load More\\u0022,\\u0022loadMoreFontSize\\u0022:16,\\u0022loadMoreTextColor\\u0022:\\u0022rgba(255,255,255,1)\\u0022,\\u0022loadMoreBgColor\\u0022:\\u0022rgba(0,0,0,1)\\u0022,\\u0022tagsFilter\\u0022:false,\\u0022tagCloudAll\\u0022:\\u0022All\\u0022,\\u0022tagCloudBgColor\\u0022:\\u0022rgba(153,153,153,1)\\u0022,\\u0022tagCloudBgColorOver\\u0022:\\u0022rgba(253,253,253,1)\\u0022,\\u0022tagCloudTextColor\\u0022:\\u0022rgba(253,253,253,1)\\u0022,\\u0022tagCloudTextColorOver\\u0022:\\u0022rgba(153,153,153,1)\\u0022,\\u0022tagCloudFontSize\\u0022:16,\\u0022modaBgColor\\u0022:\\u0022rgba(0,0,0,0.8)\\u0022,\\u0022modalIconColor\\u0022:\\u0022rgba(255,255,255,1)\\u0022,\\u0022modalIconColorHover\\u0022:\\u0022rgba(255,255,255,0.8)\\u0022,\\u0022shareFacebook\\u0022:true,\\u0022shareTwitter\\u0022:true,\\u0022sharePinterest\\u0022:true,\\u0022sliderItemDownload\\u0022:true,\\u0022shareCopyLink\\u0022:true,\\u0022sharePost\\u0022:\\u0022postlink\\u0022,\\u0022copyRProtection\\u0022:false,\\u0022copyRAlert\\u0022:\\u0022Hello, this photo is mine!\\u0022,\\u0022sliderScrollNavi\\u0022:false,\\u0022sliderFullSizeViewMode\\u0022:false,\\u0022sliderNextPrevAnimation\\u0022:\\u0022animation\\u0022,\\u0022galleryScrollPositionControll\\u0022:false,\\u0022sliderVideoAutoPlay\\u0022:false,\\u0022sliderVideoLoop\\u0022:false,\\u0022sliderItemCounterEnable\\u0022:true,\\u0022sliderCaptionSrc\\u0022:\\u0022caption\\u0022,\\u0022sliderItemTitleEnable\\u0022:false,\\u0022sliderItemTitleFontSize\\u0022:18,\\u0022sliderItemTitleTextColor\\u0022:\\u0022rgba(255,255,255,1)\\u0022,\\u0022itemCounterColor\\u0022:\\u0022rgba(255,255,255,1)\\u0022,\\u0022sliderThumbBarEnable\\u0022:true,\\u0022sliderThumbBarHoverColor\\u0022:\\u0022rgba(240,240,240,1)\\u0022,\\u0022sliderBgColor\\u0022:\\u0022rgba(0,0,0,0.8)\\u0022,\\u0022sliderPreloaderColor\\u0022:\\u0022rgba(240,240,240,1)\\u0022,\\u0022sliderHeaderFooterBgColor\\u0022:\\u0022rgba(0,0,0,0.4)\\u0022,\\u0022sliderNavigationColor\\u0022:\\u0022rgba(0,0,0,1)\\u0022,\\u0022sliderNavigationColorOver\\u0022:\\u0022rgba(255,255,255,1)\\u0022,\\u0022sliderNavigationIconColor\\u0022:\\u0022rgba(255,255,255,1)\\u0022,\\u0022sliderNavigationIconColorOver\\u0022:\\u0022rgba(0,0,0,1)\\u0022,\\u0022sliderSlideshow\\u0022:true,\\u0022sliderSlideshowDelay\\u0022:8,\\u0022slideshowIndicatorColor\\u0022:\\u0022rgba(255,255,255,1)\\u0022,\\u0022slideshowIndicatorColorBg\\u0022:\\u0022rgba(255,255,255,0.5)\\u0022,\\u0022sliderThumbSubMenuBackgroundColor\\u0022:\\u0022rgba(255,255,255,0)\\u0022,\\u0022sliderThumbSubMenuBackgroundColorOver\\u0022:\\u0022rgba(255,255,255,1)\\u0022,\\u0022sliderThumbSubMenuIconColor\\u0022:\\u0022rgba(255,255,255,1)\\u0022,\\u0022sliderThumbSubMenuIconHoverColor\\u0022:\\u0022rgba(0,0,0,1)\\u0022,\\u0022sliderSocialShareEnabled\\u0022:false,\\u0022sliderZoomEnable\\u0022:true,\\u0022sliderFullscreenEnabled\\u0022:true,\\u0022skin\\u0022:\\u0022justified\\u0022}\",\"useClobalSettings\":true,\"sharePost\":\"postlink\",\"sliderSocialShareEnabled\":false}<\/script><script>(function(){if(window.PGC_SGB && window.PGC_SGB.searcher){window.PGC_SGB.searcher.initBlocks()}})()<\/script><\/div>\n\n\n<h2 class=\"wp-block-heading\" id=\"historia-de-origen\">Historia de Origen<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">El Hokkaido es uno de los perros m\u00e1s antiguos y raros de Jap\u00f3n. El desarrollo y la formaci\u00f3n de la raza comenzaron ya en la Edad de Bronce (300 a.C.) y continuaron durante el periodo Kamakura (1185-1333). Se sabe que en esa \u00e9poca los perros eran criados por los ainu, los habitantes originales de Jap\u00f3n, de donde surgi\u00f3 el segundo nombre de la raza \u00abAinu-Ken\u00bb. Este nombre tambi\u00e9n se considera oficial y correcto. El nombre \u00abHokkaido\u00bb no se consolid\u00f3 hasta 1937, cuando la raza se convirti\u00f3 en monumento natural y tesoro nacional de Jap\u00f3n. Desde que se consagr\u00f3 ese estatus para estos perros, est\u00e1 prohibido sacarlos del pa\u00eds.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En aquella \u00e9poca, el Ainu-Ken era un ayudante indispensable para pastores, cazadores e incluso pescadores. Un perro fuerte, resistente y \u00e1gil era un verdadero peligro para las grandes bestias. A menudo cazaba osos, y durante la temporada de desove en primavera, el Hokkaido ayudaba a capturar salmones. Los perros de Hokkaido sol\u00edan acompa\u00f1ar a los lugare\u00f1os y a los emigrantes de la isla de Honshu al pueblo de Hokkaido. El Inu-ken se hizo famoso en todo el pa\u00eds en 1902, cuando 199 soldados murieron de congelaci\u00f3n en las monta\u00f1as de Hakkodo durante unos ejercicios. Sus cuerpos s\u00f3lo se encontraron gracias a los perros de Hokkaido, que ten\u00edan un agudo sentido del olfato y una excelente adaptabilidad al duro y g\u00e9lido clima. En 1964 la raza fue reconocida por la Federaci\u00f3n Canina Internacional. Se le atribuy\u00f3 al grupo de los Spitz y a las razas de tipo primitivo: la raza se form\u00f3 bajo la influencia de diversos factores, de forma natural y sin intervenci\u00f3n humana.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Son perros brillantes y valientes. Durante la Segunda Guerra Mundial, los Hokkaido eran combatientes tan entrenados que se utilizaban como informantes para localizar a los enemigos.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"apariencia\">Apariencia<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">El Hokkaido es un perro de tama\u00f1o medio, con una constituci\u00f3n musculosa y huesos fuertes. El cuerpo es alargado, la relaci\u00f3n entre la altura a la cruz y la longitud del cuerpo es de 10\/11. Su aspecto es similar al del Shiba-Inu japon\u00e9s, s\u00f3lo que el Hokkaido es algo m\u00e1s grande. El cr\u00e1neo es ancho y la frente es ligeramente aplanada. Hocico cuneiforme, p\u00f3mulos bien definidos. Las orejas son altas, triangulares, ligeramente inclinadas hacia adelante, de tama\u00f1o peque\u00f1o. El cuello y la espalda son firmes y musculosos. El pecho est\u00e1 bien desarrollado y el abdomen es tenso. La cola es gruesa; un conjunto alto puede ser retorcido o en forma de hoz en la espalda. El pelaje es doble: la lana es recta y r\u00edgida, pero la capa interna es suave. El manto de la cola es diferente; all\u00ed es largo y grueso, en contraste con el resto del cuerpo.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"personaje\">Personaje<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">El Hokkaido es una raza de perro con una personalidad complicada que incluye cualidades opuestas. Son inteligentes, incre\u00edblemente inteligentes, cari\u00f1osos y, al mismo tiempo, alegres y peligrosos. Para su amo, el Hokkaido ser\u00e1 una monta\u00f1a y nunca har\u00e1 da\u00f1o. Todos los perros necesitan amor, cuidados y una excelente educaci\u00f3n; as\u00ed no se consigue un perro incontrolable y agresivo. El perro de Hokkaido tiene un instinto de caza desarrollado, es equilibrado y confiado, adaptado a cualquier clima.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Con otros animales, las relaciones son dif\u00edciles debido a su peculiar temperamento. Los ni\u00f1os de cualquier edad se llevar\u00e1n bien, los juegos en\u00e9rgicos y la diversi\u00f3n en familia, justo lo que necesita el Hokkaido. Es mejor tener un perro Hokkaido en casa por su tama\u00f1o y disposici\u00f3n.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"cuidado\">Cuidado<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">El Hokkaido debe acostumbrarse a todos los procedimientos de higiene habituales desde una edad temprana. Debido a la abundancia de pelo, se recomienda peinar a la mascota varias veces a la semana y diariamente durante el periodo de muda. Limpie las orejas cuando sea necesario y vigile el estado de los ojos.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"formacion\">Formaci\u00f3n<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Una cosa interesante que hay que recordar sobre el Hokkaido es que es un perro que s\u00f3lo obedece a su due\u00f1o. Desgraciadamente, si cree que tiene un car\u00e1cter demasiado blando, este perro no es para usted. En el caso del Hokkaido, se necesita severidad, cualidades de liderazgo y paciencia.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Memorizar\u00e1 bien las \u00f3rdenes, har\u00e1 absolutamente todo lo que le pidas, pero s\u00f3lo si Hokkaido conf\u00eda plenamente en ti. El Ainu-can est\u00e1 lleno de energ\u00eda y necesita frecuentes paseos con actividad f\u00edsica.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"enfermedades-comunes\">Enfermedades Comunes<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Desde su formaci\u00f3n, la raza Hokkaido ha pasado por muchas cosas y ahora tiene una inmunidad bastante fuerte y resistencia a las patolog\u00edas hereditarias. Sin embargo, muchas enfermedades son caracter\u00edsticas de estos perros:<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>displasia de cadera y de codo;<\/li><li>criptorquidia;<\/li><li>anomal\u00eda ocular del collie;<\/li><li>hypodontia;<\/li><li>reacciones al\u00e9rgicas.<\/li><\/ul>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"nutricion\">Nutrici\u00f3n<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Existen algunos problemas a la hora de elegir una dieta adecuada para el Hokkaido debido a su origen cerca de las islas. Hay que tener muy en cuenta la alimentaci\u00f3n del perro porque la raza es propensa a las reacciones al\u00e9rgicas (la mayor\u00eda de las carnes provocan alergias, y algunas papillas se digieren mal). Por lo tanto, la dieta debe ser equilibrada y elegida lo m\u00e1s correctamente posible.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Sobre todo pescado, arroz y marisco. No experimente con la salud de su mascota, para no ponerla en una mala situaci\u00f3n. Habla con un criador o veterinario con experiencia que pueda ayudarte con las opciones nutricionales, para que tu mascota no pase hambre.<\/p>\n\n\n\n","protected":false},"excerpt":{"rendered":"<p>El Hokkaido es una raza de perro con una personalidad complicada que incluye cualidades opuestas. Son inteligentes, incre\u00edblemente inteligentes, cari\u00f1osos y, al mismo tiempo, alegres y peligrosos. Para su amo, el Hokkaido ser\u00e1 una monta\u00f1a y nunca har\u00e1 da\u00f1o. Todos los perros necesitan amor, cuidados y una excelente educaci\u00f3n; as\u00ed no se consigue un perro [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":3265,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"pgc_sgb_lightbox_settings":"","footnotes":""},"categories":[271],"tags":[224,233,250],"class_list":["post-3274","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-razas-de-perros","tag-razas-de-perros-de-caza","tag-razas-de-perros-japoneses","tag-razas-de-perros-medianos"],"acf":[],"_links":{"self":[{"href":"https:\/\/fello.pet\/es\/wp-json\/wp\/v2\/posts\/3274","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/fello.pet\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/fello.pet\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/fello.pet\/es\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/fello.pet\/es\/wp-json\/wp\/v2\/comments?post=3274"}],"version-history":[{"count":3,"href":"https:\/\/fello.pet\/es\/wp-json\/wp\/v2\/posts\/3274\/revisions"}],"predecessor-version":[{"id":3278,"href":"https:\/\/fello.pet\/es\/wp-json\/wp\/v2\/posts\/3274\/revisions\/3278"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/fello.pet\/es\/wp-json\/wp\/v2\/media\/3265"}],"wp:attachment":[{"href":"https:\/\/fello.pet\/es\/wp-json\/wp\/v2\/media?parent=3274"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/fello.pet\/es\/wp-json\/wp\/v2\/categories?post=3274"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/fello.pet\/es\/wp-json\/wp\/v2\/tags?post=3274"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}