
{"id":1779,"date":"2022-04-06T15:40:49","date_gmt":"2022-04-06T15:40:49","guid":{"rendered":"https:\/\/fello.pet\/?p=1779"},"modified":"2022-04-06T15:50:44","modified_gmt":"2022-04-06T15:50:44","slug":"dogo-mallorquin","status":"publish","type":"post","link":"https:\/\/fello.pet\/es\/dogo-mallorquin\/","title":{"rendered":"Dogo Mallorqu\u00edn"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><strong><em>Los dogos mallorquines son grandes guardianes y protectores. Est\u00e1n dispuestos a vigilar a su due\u00f1o y a su familia hasta el final; no dejan que los extra\u00f1os se acerquen a su territorio. Sin embargo, si no hay raz\u00f3n para la ira y la agresi\u00f3n, nunca la mostrar\u00e1n. Son estupendos con los ni\u00f1os, activos como para pasear y jugar mucho. Nunca ladran sin motivo.<\/em><\/strong><\/p>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-8f761849 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\"><h2 class=\"simpletoc-title\">Tabla de \u0421ontenido<\/h2>\n<ul class=\"simpletoc-list\">\n<li><a href=\"#informacion-de-la-raza\">Informaci\u00f3n de la Raza<\/a>\n<\/li>\n<li><a href=\"#fotos-de-la-raza\">Fotos de la Raza<\/a>\n<\/li>\n<li><a href=\"#historia-de-origen\">Historia de Origen<\/a>\n<\/li>\n<li><a href=\"#apariencia\">Apariencia<\/a>\n<\/li>\n<li><a href=\"#personaje\">Personaje<\/a>\n<\/li>\n<li><a href=\"#cuidado\">Cuidado<\/a>\n<\/li>\n<li><a href=\"#formacion\">Formaci\u00f3n<\/a>\n<\/li>\n<li><a href=\"#enfermedades-comunes\">Enfermedades Comunes<\/a>\n<\/li>\n<li><a href=\"#nutricion\">Nutrici\u00f3n<\/a>\n<\/li><\/ul><\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<h2 class=\"wp-block-heading\" id=\"informacion-de-la-raza\">Informaci\u00f3n de la Raza<\/h2>\n\n\n\n<figure class=\"wp-block-table alignleft\" style=\"font-size:18px\"><table class=\"has-fixed-layout\"><tbody><tr><td>Otro Nombre<\/td><td>Ca de Bou,<br>Presa mallorqu\u00edn<\/td><\/tr><tr><td>Origen<\/td><td>Espa\u00f1a<\/td><\/tr><tr><td>Altura<\/td><td>Machos 55-58 cm<br>Hembras 52-55 cm<\/td><\/tr><tr><td>Peso<\/td><td>Machos 35-38 kg<br>Hembras 30-34 kg<\/td><\/tr><tr><td>Pelo<\/td><td>Corto, r\u00edgido al tacto<\/td><\/tr><tr><td>Color<\/td><td>Tigre, ciervo y negro<\/td><\/tr><tr><td>Esperanza de Vida<\/td><td>9-12 a\u00f1os<\/td><\/tr><tr><td>Clasificaci\u00f3n FCI<\/td><td>Perros tipo pinscher y schnauzer &#8211; Molosoides &#8211; Perros tipo monta\u00f1a y boyeros suizos<\/td><\/tr><tr><td>Grupo<\/td><td>Perros de guardia, perros de protecci\u00f3n<\/td><\/tr><tr><td>Precio<\/td><td>$300-900<\/td><\/tr><\/tbody><\/table><\/figure>\n<\/div>\n<\/div>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"fotos-de-la-raza\">Fotos de la Raza<\/h2>\n\n\n<div class=\"pgc-sgb-cb wp-block-pgcsimplygalleryblock-justified \" data-gallery-id=\"b9b55770\"><div class=\"sgb-preloader\" id=\"pr_b9b55770\">\n\t<div class=\"sgb-square\" style=\"background:#d4d4d4\"><\/div>\n\t<div class=\"sgb-square\" style=\"background:#d4d4d4\"><\/div>\n\t<div class=\"sgb-square\" style=\"background:#d4d4d4\"><\/div>\n\t<div class=\"sgb-square\" style=\"background:#d4d4d4\"><\/div><\/div><div class=\"simply-gallery-amp pgc_sgb_slider \"><noscript><div class=\"sgb-gallery\"><div class=\"sgb-item\"><a href=\"https:\/\/fello.pet\/?attachment_id=1776#main\" target=\"_blank\"><img decoding=\"async\" alt=\"\" width=\"564\" height=\"371\" loading=\"lazy\" src=\"https:\/\/fello.pet\/wp-content\/uploads\/2022\/04\/Ca-de-Bou-1.jpg\" srcset=\",https:\/\/fello.pet\/wp-content\/uploads\/2022\/04\/Ca-de-Bou-1.jpg 564w\" sizes=\"auto, 250px\"\/><\/a><\/div><div class=\"sgb-item\"><a href=\"https:\/\/fello.pet\/?attachment_id=1774#main\" target=\"_blank\"><img decoding=\"async\" alt=\"Ca de Bou\" width=\"300\" height=\"400\" loading=\"lazy\" src=\"https:\/\/fello.pet\/wp-content\/uploads\/2022\/04\/Ca-de-Bou-2-300x400.jpg\" srcset=\"https:\/\/fello.pet\/wp-content\/uploads\/2022\/04\/Ca-de-Bou-2-300x400.jpg 300w,https:\/\/fello.pet\/wp-content\/uploads\/2022\/04\/Ca-de-Bou-2.jpg 564w\" sizes=\"auto, 250px\"\/><\/a><\/div><div class=\"sgb-item\"><a href=\"https:\/\/fello.pet\/?attachment_id=1772#main\" target=\"_blank\"><img decoding=\"async\" alt=\"Ca de Bou\" width=\"300\" height=\"400\" loading=\"lazy\" src=\"https:\/\/fello.pet\/wp-content\/uploads\/2022\/04\/Ca-de-Bou-3-300x400.jpg\" srcset=\"https:\/\/fello.pet\/wp-content\/uploads\/2022\/04\/Ca-de-Bou-3-300x400.jpg 300w,https:\/\/fello.pet\/wp-content\/uploads\/2022\/04\/Ca-de-Bou-3.jpg 450w\" sizes=\"auto, 250px\"\/><\/a><\/div><div class=\"sgb-item\"><a href=\"https:\/\/fello.pet\/?attachment_id=1770#main\" target=\"_blank\"><img decoding=\"async\" alt=\"Ca de Bou\" width=\"555\" height=\"369\" loading=\"lazy\" src=\"https:\/\/fello.pet\/wp-content\/uploads\/2022\/04\/Ca-de-Bou-4.jpg\" srcset=\",https:\/\/fello.pet\/wp-content\/uploads\/2022\/04\/Ca-de-Bou-4.jpg 555w\" sizes=\"auto, 250px\"\/><\/a><\/div><\/div><\/noscript><\/div><script type=\"application\/json\" class=\"sgb-data\">{\"lastRowFill\":true,\"collectionThumbRecomendedHeight\":300,\"collectionThumbMiniScreenScale\":true,\"externalLink\":false,\"collectionThumbSubMenuDownload\":false,\"collectionThumbSubMenuShare\":false,\"galleryType\":\"pgc_sgb_justified\",\"galleryId\":\"b9b55770\",\"images\":[{\"id\":1776,\"title\":\"Ca de Bou 1\",\"url\":\"https:\/\/fello.pet\/wp-content\/uploads\/2022\/04\/Ca-de-Bou-1.jpg\",\"link\":\"https:\/\/fello.pet\/?attachment_id=1776#main\",\"alt\":\"\",\"description\":\"\",\"caption\":\"\",\"mime\":\"image\/jpeg\",\"type\":\"image\",\"width\":564,\"height\":371,\"sizes\":{\"thumbnail\":{\"url\":\"https:\/\/fello.pet\/wp-content\/uploads\/2022\/04\/Ca-de-Bou-1-280x280.jpg\",\"height\":280,\"width\":280,\"orientation\":\"landscape\"},\"full\":{\"url\":\"https:\/\/fello.pet\/wp-content\/uploads\/2022\/04\/Ca-de-Bou-1.jpg\",\"height\":371,\"width\":564,\"orientation\":\"landscape\"}},\"meta\":false,\"postlink\":\"https:\/\/fello.pet\/?attachment_id=1776#main\"},{\"id\":1774,\"title\":\"Ca de Bou 2\",\"url\":\"https:\/\/fello.pet\/wp-content\/uploads\/2022\/04\/Ca-de-Bou-2.jpg\",\"link\":\"https:\/\/fello.pet\/?attachment_id=1774#main\",\"alt\":\"Ca de Bou\",\"description\":\"\",\"caption\":\"\",\"mime\":\"image\/jpeg\",\"type\":\"image\",\"width\":564,\"height\":752,\"sizes\":{\"thumbnail\":{\"url\":\"https:\/\/fello.pet\/wp-content\/uploads\/2022\/04\/Ca-de-Bou-2-280x280.jpg\",\"height\":280,\"width\":280,\"orientation\":\"landscape\"},\"medium\":{\"url\":\"https:\/\/fello.pet\/wp-content\/uploads\/2022\/04\/Ca-de-Bou-2-300x400.jpg\",\"height\":400,\"width\":300,\"orientation\":\"portrait\"},\"full\":{\"url\":\"https:\/\/fello.pet\/wp-content\/uploads\/2022\/04\/Ca-de-Bou-2.jpg\",\"height\":752,\"width\":564,\"orientation\":\"portrait\"}},\"meta\":false,\"postlink\":\"https:\/\/fello.pet\/?attachment_id=1774#main\"},{\"id\":1772,\"title\":\"Ca de Bou\",\"url\":\"https:\/\/fello.pet\/wp-content\/uploads\/2022\/04\/Ca-de-Bou-3.jpg\",\"link\":\"https:\/\/fello.pet\/?attachment_id=1772#main\",\"alt\":\"Ca de Bou\",\"description\":\"\",\"caption\":\"\",\"mime\":\"image\/jpeg\",\"type\":\"image\",\"width\":450,\"height\":600,\"sizes\":{\"thumbnail\":{\"url\":\"https:\/\/fello.pet\/wp-content\/uploads\/2022\/04\/Ca-de-Bou-3-280x280.jpg\",\"height\":280,\"width\":280,\"orientation\":\"landscape\"},\"medium\":{\"url\":\"https:\/\/fello.pet\/wp-content\/uploads\/2022\/04\/Ca-de-Bou-3-300x400.jpg\",\"height\":400,\"width\":300,\"orientation\":\"portrait\"},\"full\":{\"url\":\"https:\/\/fello.pet\/wp-content\/uploads\/2022\/04\/Ca-de-Bou-3.jpg\",\"height\":600,\"width\":450,\"orientation\":\"portrait\"}},\"meta\":false,\"postlink\":\"https:\/\/fello.pet\/?attachment_id=1772#main\"},{\"id\":1770,\"title\":\"Ca de Bou\",\"url\":\"https:\/\/fello.pet\/wp-content\/uploads\/2022\/04\/Ca-de-Bou-4.jpg\",\"link\":\"https:\/\/fello.pet\/?attachment_id=1770#main\",\"alt\":\"Ca de Bou\",\"description\":\"\",\"caption\":\"\",\"mime\":\"image\/jpeg\",\"type\":\"image\",\"width\":555,\"height\":369,\"sizes\":{\"thumbnail\":{\"url\":\"https:\/\/fello.pet\/wp-content\/uploads\/2022\/04\/Ca-de-Bou-4-280x280.jpg\",\"height\":280,\"width\":280,\"orientation\":\"landscape\"},\"full\":{\"url\":\"https:\/\/fello.pet\/wp-content\/uploads\/2022\/04\/Ca-de-Bou-4.jpg\",\"height\":369,\"width\":555,\"orientation\":\"landscape\"}},\"meta\":false,\"postlink\":\"https:\/\/fello.pet\/?attachment_id=1770#main\"}],\"itemsMetaDataCollection\":[],\"galleryData\":\"{\\u0022pageMode\\u0022:false,\\u0022lastRowFill\\u0022:true,\\u0022collectionThumbRecomendedHeight\\u0022:300,\\u0022collectionThumbMiniScreenScale\\u0022:true,\\u0022thumbSpacing\\u0022:5,\\u0022externalLink\\u0022:false,\\u0022externalLinkDefName\\u0022:\\u0022Read More\\u0022,\\u0022externalLinkTextColor\\u0022:\\u0022rgba(0,0,0,1)\\u0022,\\u0022externalLinkBgColor\\u0022:\\u0022rgba(255,255,255,1)\\u0022,\\u0022externalLinkFontSize\\u0022:18,\\u0022captions\\u0022:true,\\u0022captionSrc\\u0022:\\u0022caption\\u0022,\\u0022captionHAlign\\u0022:\\u0022top\\u0022,\\u0022collectionthumbHoverTitleFontSize\\u0022:18,\\u0022collectionthumbRoundedCorners\\u0022:0,\\u0022collectionthumbHoverTitleTextColor\\u0022:\\u0022rgba(255,255,255,1)\\u0022,\\u0022collectionthumbHoverTitleTextBgColor\\u0022:\\u0022rgba(0,0,0,0.8)\\u0022,\\u0022collectionthumbHoverBgColor\\u0022:\\u0022rgba(0,0,0,0.4)\\u0022,\\u0022collectionThumbSubMenuDownload\\u0022:false,\\u0022collectionThumbSubMenuShare\\u0022:false,\\u0022collectionThumbSubMenuBgColor\\u0022:\\u0022rgba(0,0,0,0.4)\\u0022,\\u0022collectionThumbSubMenuBgColorHover\\u0022:\\u0022rgba(255,255,255,1)\\u0022,\\u0022collectionThumbSubMenuIconColor\\u0022:\\u0022rgba(255,255,255,1)\\u0022,\\u0022collectionThumbSubMenuIconColorHover\\u0022:\\u0022rgba(0,0,0,1)\\u0022,\\u0022settingsModalIsOpen\\u0022:false,\\u0022galleryType\\u0022:\\u0022pgc_sgb_justified\\u0022,\\u0022align\\u0022:\\u0022\\u0022,\\u0022galleryId\\u0022:\\u0022b9b55770\\u0022,\\u0022tagsListCustomMode\\u0022:false,\\u0022initGalleryByFirstTag\\u0022:false,\\u0022deepLinkingForTag\\u0022:false,\\u0022galleryTagsList\\u0022:[],\\u0022useClobalSettings\\u0022:true,\\u0022orderBy\\u0022:\\u0022custom\\u0022,\\u0022deepLinking\\u0022:false,\\u0022useLightbox\\u0022:true,\\u0022thumbClickAction\\u0022:\\u0022useLightbox\\u0022,\\u0022numItemsDisplayed\\u0022:0,\\u0022lazyLoading\\u0022:true,\\u0022contentNoPadding\\u0022:false,\\u0022galleryPreloaderColor\\u0022:\\u0022rgba(230,230,230,1)\\u0022,\\u0022galleryBgColor\\u0022:\\u0022rgba(0,0,0,0)\\u0022,\\u0022galleryBorderRadius\\u0022:0,\\u0022customCSS\\u0022:\\u0022\\u0022,\\u0022itemsPerPage\\u0022:20,\\u0022loadMoreDefName\\u0022:\\u0022Load More\\u0022,\\u0022loadMoreFontSize\\u0022:16,\\u0022loadMoreTextColor\\u0022:\\u0022rgba(255,255,255,1)\\u0022,\\u0022loadMoreBgColor\\u0022:\\u0022rgba(0,0,0,1)\\u0022,\\u0022tagsFilter\\u0022:false,\\u0022tagCloudAll\\u0022:\\u0022All\\u0022,\\u0022tagCloudBgColor\\u0022:\\u0022rgba(153,153,153,1)\\u0022,\\u0022tagCloudBgColorOver\\u0022:\\u0022rgba(253,253,253,1)\\u0022,\\u0022tagCloudTextColor\\u0022:\\u0022rgba(253,253,253,1)\\u0022,\\u0022tagCloudTextColorOver\\u0022:\\u0022rgba(153,153,153,1)\\u0022,\\u0022tagCloudFontSize\\u0022:16,\\u0022modaBgColor\\u0022:\\u0022rgba(0,0,0,0.8)\\u0022,\\u0022modalIconColor\\u0022:\\u0022rgba(255,255,255,1)\\u0022,\\u0022modalIconColorHover\\u0022:\\u0022rgba(255,255,255,0.8)\\u0022,\\u0022shareFacebook\\u0022:true,\\u0022shareTwitter\\u0022:true,\\u0022sharePinterest\\u0022:true,\\u0022sliderItemDownload\\u0022:true,\\u0022shareCopyLink\\u0022:true,\\u0022sharePost\\u0022:\\u0022postlink\\u0022,\\u0022copyRProtection\\u0022:false,\\u0022copyRAlert\\u0022:\\u0022Hello, this photo is mine!\\u0022,\\u0022sliderScrollNavi\\u0022:false,\\u0022sliderFullSizeViewMode\\u0022:false,\\u0022sliderNextPrevAnimation\\u0022:\\u0022animation\\u0022,\\u0022galleryScrollPositionControll\\u0022:false,\\u0022sliderVideoAutoPlay\\u0022:false,\\u0022sliderVideoLoop\\u0022:false,\\u0022sliderItemCounterEnable\\u0022:true,\\u0022sliderCaptionSrc\\u0022:\\u0022caption\\u0022,\\u0022sliderItemTitleEnable\\u0022:false,\\u0022sliderItemTitleFontSize\\u0022:18,\\u0022sliderItemTitleTextColor\\u0022:\\u0022rgba(255,255,255,1)\\u0022,\\u0022itemCounterColor\\u0022:\\u0022rgba(255,255,255,1)\\u0022,\\u0022sliderThumbBarEnable\\u0022:true,\\u0022sliderThumbBarHoverColor\\u0022:\\u0022rgba(240,240,240,1)\\u0022,\\u0022sliderBgColor\\u0022:\\u0022rgba(0,0,0,0.8)\\u0022,\\u0022sliderPreloaderColor\\u0022:\\u0022rgba(240,240,240,1)\\u0022,\\u0022sliderHeaderFooterBgColor\\u0022:\\u0022rgba(0,0,0,0.4)\\u0022,\\u0022sliderNavigationColor\\u0022:\\u0022rgba(0,0,0,1)\\u0022,\\u0022sliderNavigationColorOver\\u0022:\\u0022rgba(255,255,255,1)\\u0022,\\u0022sliderNavigationIconColor\\u0022:\\u0022rgba(255,255,255,1)\\u0022,\\u0022sliderNavigationIconColorOver\\u0022:\\u0022rgba(0,0,0,1)\\u0022,\\u0022sliderSlideshow\\u0022:true,\\u0022sliderSlideshowDelay\\u0022:8,\\u0022slideshowIndicatorColor\\u0022:\\u0022rgba(255,255,255,1)\\u0022,\\u0022slideshowIndicatorColorBg\\u0022:\\u0022rgba(255,255,255,0.5)\\u0022,\\u0022sliderThumbSubMenuBackgroundColor\\u0022:\\u0022rgba(255,255,255,0)\\u0022,\\u0022sliderThumbSubMenuBackgroundColorOver\\u0022:\\u0022rgba(255,255,255,1)\\u0022,\\u0022sliderThumbSubMenuIconColor\\u0022:\\u0022rgba(255,255,255,1)\\u0022,\\u0022sliderThumbSubMenuIconHoverColor\\u0022:\\u0022rgba(0,0,0,1)\\u0022,\\u0022sliderSocialShareEnabled\\u0022:false,\\u0022sliderZoomEnable\\u0022:true,\\u0022sliderFullscreenEnabled\\u0022:true,\\u0022skin\\u0022:\\u0022justified\\u0022}\",\"useClobalSettings\":true,\"sharePost\":\"postlink\",\"sliderSocialShareEnabled\":false}<\/script><script>(function(){if(window.PGC_SGB && window.PGC_SGB.searcher){window.PGC_SGB.searcher.initBlocks()}})()<\/script><\/div>\n\n\n<h2 class=\"wp-block-heading\" id=\"historia-de-origen\">Historia de Origen<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">En la \u00e9poca de la navegaci\u00f3n y los descubrimientos, la gente no s\u00f3lo compart\u00eda el grano u otras posesiones materiales, sino tambi\u00e9n los animales dom\u00e9sticos, especialmente los de guardia, que se utilizaban en los puertos y bajo los barcos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Uno de estos perros era el mast\u00edn ib\u00e9rico, antiguo pariente del dogo mallorqu\u00edn. Esta raza luchadora realizaba una excelente labor de defensa del territorio contra piratas y bandoleros.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En 1230 los perros salieron de campa\u00f1a con el rey Jaime I como escoltas y as\u00ed acabaron en las Islas Baleares. Pronto, las tierras pasaron a manos de Gran Breta\u00f1a, que las pobl\u00f3 num\u00e9ricamente y comenz\u00f3 a cruzar sus perros con los nativos. As\u00ed naci\u00f3 la raza dogo mallorqu\u00edn.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Cuando lleg\u00f3 la \u00e9poca de la popularidad de la tauromaquia, se necesitaban perros que sujetaran al toro antes de la lidia, a los toros de lidia y a otros depredadores salvajes. Para ello, se empez\u00f3 a utilizar el Perro Dogo Mallorqu\u00edn, que hizo un excelente trabajo. Ahora los representantes de la raza son famosos en todo el mundo y se utilizan como defensores del hogar.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"apariencia\">Apariencia<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">A pesar de su estatura relativamente peque\u00f1a, el tama\u00f1o del perro es intimidante y formidable debido a su complexi\u00f3n robusta y su musculatura. Existe un dimorfismo sexual: la altura en los machos es de 55-58 cm, en las hembras de 52-55 cm. Tambi\u00e9n en cuanto al peso: Los machos pueden llegar a pesar entre 35-38 kg, las hembras unos 30-34 kg.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El perro tiene m\u00fasculos masticadores bien definidos en la cara. Las orejas son de implantaci\u00f3n amplia; es habitual que no se recorten. El pelaje es corto pero r\u00edgido y ce\u00f1ido Perro Dogo Mallorqu\u00edn. El color puede ser tigre, p\u00e1lido, negro, con manchas blancas en el pecho y las patas. Puede formarse una m\u00e1scara negra en el hocico.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"personaje\">Personaje<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Los dogos mallorquines son grandes guardianes y protectores. Est\u00e1n dispuestos a vigilar a su due\u00f1o y a su familia hasta el final; no dejan que los extra\u00f1os se acerquen a su territorio.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Sin embargo, si no hay raz\u00f3n para la ira y la agresi\u00f3n, nunca la mostrar\u00e1n. Son estupendos con los ni\u00f1os, activos como para pasear y jugar mucho. Nunca ladran sin motivo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Est\u00e1n dispuestos a compartir el territorio con otros animales de la casa, pero seguir\u00e1n siendo l\u00edderes y los tratar\u00e1n como objetos que hay que proteger. Los representantes de la raza obedecen a su due\u00f1o y a los miembros de la familia en la que viven. Son leales, alegres y equilibrados. Los dogos mallorquines se mueven mucho, corren mucho y siempre quieren estar activos, por lo que debe estar preparado para un vigor excesivo.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"cuidado\">Cuidado<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Un dogo mallorqu\u00edn puede vivir tanto en un apartamento como en un recinto de la propiedad. Lo principal es que siempre tenga su lugar particular, donde habr\u00e1 cuencos, juguetes y un lugar para dormir.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El punto principal del cuidado de un perro es la necesidad de ejercicio. Si la mascota va a vivir en un apartamento, necesita salir al exterior con frecuencia y durante largos periodos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El pelo debe cepillarse cada dos d\u00edas con un cepillo especial. Durante la muda, se recomienda utilizar un secador para eliminar mejor el pelo muerto.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">No se recomienda ba\u00f1arlo a menudo; con dos veces al a\u00f1o es suficiente. Sin embargo, hay que tener en cuenta la limpieza del perro. Compruebe regularmente el estado de los ojos, observe si est\u00e1n enrojecidos o llorosos. No permita que el dogo mallorqu\u00edn est\u00e9 en una corriente de aire.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Una vez a la semana, hay que examinar la cavidad bucal y cepillar los dientes. Una vez al mes, es aconsejable recortar las garras. Una vez a la semana, las orejas deben limpiarse suavemente con una varilla auricular.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"formacion\">Formaci\u00f3n<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Es necesario mostrar liderazgo y no permitir a su cachorro el m\u00e1s m\u00ednimo capricho desde una edad temprana. En primer lugar, hay que acostumbrar al perro a otras personas y animales, y despu\u00e9s se puede intentar acostumbrarlo poco a poco y de forma discreta al collar y la correa. Ser\u00eda \u00fatil que elogiara a su perro cuando obedeciera las \u00f3rdenes correctamente.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Los especialistas recomiendan realizar un curso adicional de guardia, y entonces el dogo mallorqu\u00edn podr\u00e1 demostrar plenamente sus habilidades como guardia del territorio.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"enfermedades-comunes\">Enfermedades Comunes<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Los dogos mallorquines gozan de buena salud, pero pueden tener enfermedades propias de la raza: displasia de cadera, dermatitis, trastornos estomacales.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"nutricion\">Nutrici\u00f3n<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">El propietario debe elegir la mejor manera de alimentarse: comida o alimentos naturales. Se puede consultar al m\u00e9dico.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Si la segunda opci\u00f3n, entonces la base de la dieta debe consistir en la carne. Adem\u00e1s, se debe dar subproductos, pescado, frutas de temporada, verduras. En el dogo mallorqu\u00edn siempre tiene acceso a agua potable.<\/p>\n\n\n\n","protected":false},"excerpt":{"rendered":"<p>Los dogos mallorquines son grandes guardianes y protectores. Est\u00e1n dispuestos a vigilar a su due\u00f1o y a su familia hasta el final; no dejan que los extra\u00f1os se acerquen a su territorio. Sin embargo, si no hay raz\u00f3n para la ira y la agresi\u00f3n, nunca la mostrar\u00e1n. Son estupendos con los ni\u00f1os, activos como para [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":1777,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"pgc_sgb_lightbox_settings":"","footnotes":""},"categories":[271],"tags":[228,243,249,226,229,253],"class_list":["post-1779","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-razas-de-perros","tag-razas-de-perros-de-pelea","tag-razas-de-perros-de-pelo-liso","tag-razas-de-perros-grandes","tag-razas-de-perros-guardianes","tag-razas-de-perros-para-apartamentos","tag-razas-de-perros-raras"],"acf":[],"_links":{"self":[{"href":"https:\/\/fello.pet\/es\/wp-json\/wp\/v2\/posts\/1779","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/fello.pet\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/fello.pet\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/fello.pet\/es\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/fello.pet\/es\/wp-json\/wp\/v2\/comments?post=1779"}],"version-history":[{"count":2,"href":"https:\/\/fello.pet\/es\/wp-json\/wp\/v2\/posts\/1779\/revisions"}],"predecessor-version":[{"id":1781,"href":"https:\/\/fello.pet\/es\/wp-json\/wp\/v2\/posts\/1779\/revisions\/1781"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/fello.pet\/es\/wp-json\/wp\/v2\/media\/1777"}],"wp:attachment":[{"href":"https:\/\/fello.pet\/es\/wp-json\/wp\/v2\/media?parent=1779"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/fello.pet\/es\/wp-json\/wp\/v2\/categories?post=1779"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/fello.pet\/es\/wp-json\/wp\/v2\/tags?post=1779"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}